{"id":820,"date":"2020-04-26T01:35:46","date_gmt":"2020-04-26T06:35:46","guid":{"rendered":"https:\/\/boitedecom.ca\/blog\/?p=820"},"modified":"2020-05-13T01:42:54","modified_gmt":"2020-05-13T06:42:54","slug":"dropshipping-combien-argent-debuter%e2%80%af","status":"publish","type":"post","link":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/","title":{"rendered":"Dropshipping: Combien d&rsquo;argent pour d\u00e9buter?"},"content":{"rendered":"<h2>QUEL BUDGET PR\u00c9VOIR POUR D\u00c9BUTER EN DROPSHIPPING ?<\/h2>\n<p>On peut penser que le drophsipping co\u00fbte cher au d\u00e9marrage ou au contraire que cela ne co\u00fbte rien. Dans les 2 cas ces r\u00e9ponses sont fausses. Le dropshipping est un business particuli\u00e8rement accessible mais qui comprend des co\u00fbts cach\u00e9s \u00e0 ne surtout pas n\u00e9gliger!<\/p>\n<p><strong>Voici une liste des d\u00e9penses \u00e0 pr\u00e9voir :<\/strong><\/p>\n<p>1) Les frais li\u00e9s \u00e0 la boutique. La premi\u00e8re d\u00e9pense concernera l&rsquo;abonnement \u00e0 Shopify pour lequel il faut compter environ 25 \u00e0 30\u20ac\/mois. Ensuite il faudra \u00e9galement pr\u00e9voir l&rsquo;achat d&rsquo;un nom de domaine. Cette derni\u00e8re d\u00e9pense est minime puisqu&rsquo;il faut compter seulement une quinzaine d&rsquo;euros par an.<\/p>\n<p>Si vous souhaitez aller plus loin vous pouvez \u00e9ventuellement pr\u00e9voir l&rsquo;achat d&rsquo;un th\u00e8me payant pour votre <strong><a href=\"https:\/\/boitedecom.ca\/comment-creer-boutique-shopify\/\">boutique Shopify<\/a><\/strong> ou encore r\u00e9mun\u00e9rer un graphiste pour r\u00e9aliser votre logo. C&rsquo;est optionnel et cela d\u00e9pendra en grande partie de vos objectifs et\/ou de vos comp\u00e9tences.<\/p>\n<p>2) Les d\u00e9penses li\u00e9es au marketing. C&rsquo;est le p\u00f4le de d\u00e9penses le plus \u00e9lev\u00e9. Facebook ads, Snapshat ads, Google ads&#8230; Ce sont ces plateformes qui vont vous rapporter le plus de trafic pour votre boutique, mais qu&rsquo;il faut r\u00e9mun\u00e9rer. Ces d\u00e9penses peuvent rapidement monter si vous ne les utilisez pas correctement, il est donc important de bien se former sur ces plateformes avant de se lancer.<br \/>\nIl faut compter en moyenne un budget d&rsquo;environ 30$ tous les 2 jours pour chacun des produits test\u00e9s.<\/p>\n<p>3) Attention aux frais cach\u00e9s. Lorsqu\u2019un client ach\u00e8te vos produits vous ne toucherez pas l&rsquo;argent imm\u00e9diatement. Pr\u00e9voyez toujours un fond de roulement \/ un cashflow pour avancer l&rsquo;argent \u00e0 vos fournisseurs.<br \/>\nPour obtenir ce cashflow plusieurs options s&rsquo;offrent \u00e0 vous : vous pouvez utiliser des cartes de cr\u00e9dit \u00e0 d\u00e9bit diff\u00e9r\u00e9, vous pouvez mettre de l&rsquo;argent de c\u00f4t\u00e9, mais en g\u00e9n\u00e9ral il faut toujours essayer d&rsquo;optimiser un maximum votre rentabilit\u00e9 pour vous d\u00e9gager ce cashflow.<\/p>\n<p>D\u00e9pense bonus : Formez-vous constamment \/ Investissez en vous-m\u00eame ! Le dropshipping, et en g\u00e9n\u00e9ral le e-commerce, \u00e9volue \u00e0 une vitesse folle. De nouveaux outils, de nouvelles m\u00e9thodes et astuces voient le jour quotidiennement. Dans un environnement de plus en plus concurrentiel il est in\u00e9vitable de se tenir \u00e0 jour si vous souhaitez performer, tenir sur la dur\u00e9e et surtout d\u00e9buter sur de bonnes bases.<\/p>\n<p>&nbsp;<\/p>\n<h4><span style=\"color: #0085de;\"><a style=\"color: #0085de;\" href=\"https:\/\/www.shopify.com\/?ref=subscribe\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Cr\u00e9er une boutique Shopify gratuitement!<\/strong><\/a><\/span><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>QUEL BUDGET PR\u00c9VOIR POUR D\u00c9BUTER EN DROPSHIPPING ? On peut penser que le drophsipping co\u00fbte cher au d\u00e9marrage ou au contraire que cela ne co\u00fbte rien. Dans les 2 cas ces r\u00e9ponses sont fausses. Le dropshipping est un business particuli\u00e8rement accessible mais qui comprend des co\u00fbts cach\u00e9s \u00e0 ne surtout pas n\u00e9gliger! Voici une liste [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":824,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[13],"tags":[109],"class_list":{"0":"post-820","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-seo","8":"tag-dropshipping","9":"post_format-post-format-video"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dropshipping: Combien d&#039;argent pour d\u00e9buter? &#183; Boite de com<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter\u202f\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dropshipping: Combien d&#039;argent pour d\u00e9buter? &#183; Boite de com\" \/>\n<meta property=\"og:description\" content=\"QUEL BUDGET PR\u00c9VOIR POUR D\u00c9BUTER EN DROPSHIPPING ? On peut penser que le drophsipping co\u00fbte cher au d\u00e9marrage ou au contraire que cela ne co\u00fbte rien. Dans les 2 cas ces r\u00e9ponses sont fausses. Le dropshipping est un business particuli\u00e8rement accessible mais qui comprend des co\u00fbts cach\u00e9s \u00e0 ne surtout pas n\u00e9gliger! Voici une liste [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter\u202f\/\" \/>\n<meta property=\"og:site_name\" content=\"Boite de com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Boitedecom\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-26T06:35:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-13T06:42:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2020\/05\/dropshipping-coach-765756.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Boitedecom\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@boitedecomca\" \/>\n<meta name=\"twitter:site\" content=\"@boitedecomca\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Boitedecom\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/\"},\"author\":{\"name\":\"Boitedecom\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#\\\/schema\\\/person\\\/9a90a1bdb428bc354a4644e77d55d926\"},\"headline\":\"Dropshipping: Combien d&rsquo;argent pour d\u00e9buter?\",\"datePublished\":\"2020-04-26T06:35:46+00:00\",\"dateModified\":\"2020-05-13T06:42:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/\"},\"wordCount\":433,\"publisher\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dropshipping-coach-765756.jpg\",\"keywords\":[\"dropshipping\"],\"articleSection\":[\"SEO\"],\"inLanguage\":\"fr-CA\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/\",\"url\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/\",\"name\":\"Dropshipping: Combien d'argent pour d\u00e9buter? &#183; Boite de com\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dropshipping-coach-765756.jpg\",\"datePublished\":\"2020-04-26T06:35:46+00:00\",\"dateModified\":\"2020-05-13T06:42:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dropshipping-coach-765756.jpg\",\"contentUrl\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/05\\\/dropshipping-coach-765756.jpg\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/dropshipping-combien-argent-debuter%e2%80%af\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dropshipping: Combien d&rsquo;argent pour d\u00e9buter?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/\",\"name\":\"Boite de com\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#organization\",\"name\":\"Boitedecom - Agence Web\",\"url\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/agence-web.png\",\"contentUrl\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/agence-web.png\",\"width\":1000,\"height\":564,\"caption\":\"Boitedecom - Agence Web\"},\"image\":{\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Boitedecom\\\/\",\"https:\\\/\\\/x.com\\\/boitedecomca\",\"https:\\\/\\\/www.instagram.com\\\/boitedecom\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/boitedecom\",\"https:\\\/\\\/www.pinterest.com\\\/boitedecom\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/BoiteDeCom\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/#\\\/schema\\\/person\\\/9a90a1bdb428bc354a4644e77d55d926\",\"name\":\"Boitedecom\",\"url\":\"https:\\\/\\\/boitedecom.ca\\\/blog\\\/author\\\/boitedecom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dropshipping: Combien d'argent pour d\u00e9buter? &#183; Boite de com","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter\u202f\/","og_locale":"fr_CA","og_type":"article","og_title":"Dropshipping: Combien d'argent pour d\u00e9buter? &#183; Boite de com","og_description":"QUEL BUDGET PR\u00c9VOIR POUR D\u00c9BUTER EN DROPSHIPPING ? On peut penser que le drophsipping co\u00fbte cher au d\u00e9marrage ou au contraire que cela ne co\u00fbte rien. Dans les 2 cas ces r\u00e9ponses sont fausses. Le dropshipping est un business particuli\u00e8rement accessible mais qui comprend des co\u00fbts cach\u00e9s \u00e0 ne surtout pas n\u00e9gliger! Voici une liste [&hellip;]","og_url":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter\u202f\/","og_site_name":"Boite de com","article_publisher":"https:\/\/www.facebook.com\/Boitedecom\/","article_published_time":"2020-04-26T06:35:46+00:00","article_modified_time":"2020-05-13T06:42:54+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2020\/05\/dropshipping-coach-765756.jpg","type":"image\/jpeg"}],"author":"Boitedecom","twitter_card":"summary_large_image","twitter_creator":"@boitedecomca","twitter_site":"@boitedecomca","twitter_misc":{"\u00c9crit par":"Boitedecom","Estimation du temps de lecture":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/#article","isPartOf":{"@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/"},"author":{"name":"Boitedecom","@id":"https:\/\/boitedecom.ca\/blog\/#\/schema\/person\/9a90a1bdb428bc354a4644e77d55d926"},"headline":"Dropshipping: Combien d&rsquo;argent pour d\u00e9buter?","datePublished":"2020-04-26T06:35:46+00:00","dateModified":"2020-05-13T06:42:54+00:00","mainEntityOfPage":{"@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/"},"wordCount":433,"publisher":{"@id":"https:\/\/boitedecom.ca\/blog\/#organization"},"image":{"@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/#primaryimage"},"thumbnailUrl":"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2020\/05\/dropshipping-coach-765756.jpg","keywords":["dropshipping"],"articleSection":["SEO"],"inLanguage":"fr-CA"},{"@type":"WebPage","@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/","url":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/","name":"Dropshipping: Combien d'argent pour d\u00e9buter? &#183; Boite de com","isPartOf":{"@id":"https:\/\/boitedecom.ca\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/#primaryimage"},"image":{"@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/#primaryimage"},"thumbnailUrl":"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2020\/05\/dropshipping-coach-765756.jpg","datePublished":"2020-04-26T06:35:46+00:00","dateModified":"2020-05-13T06:42:54+00:00","breadcrumb":{"@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/#primaryimage","url":"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2020\/05\/dropshipping-coach-765756.jpg","contentUrl":"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2020\/05\/dropshipping-coach-765756.jpg","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/boitedecom.ca\/blog\/dropshipping-combien-argent-debuter%e2%80%af\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/boitedecom.ca\/blog\/home\/"},{"@type":"ListItem","position":2,"name":"Dropshipping: Combien d&rsquo;argent pour d\u00e9buter?"}]},{"@type":"WebSite","@id":"https:\/\/boitedecom.ca\/blog\/#website","url":"https:\/\/boitedecom.ca\/blog\/","name":"Boite de com","description":"","publisher":{"@id":"https:\/\/boitedecom.ca\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boitedecom.ca\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/boitedecom.ca\/blog\/#organization","name":"Boitedecom - Agence Web","url":"https:\/\/boitedecom.ca\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/boitedecom.ca\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2017\/07\/agence-web.png","contentUrl":"https:\/\/boitedecom.ca\/blog\/wp-content\/uploads\/2017\/07\/agence-web.png","width":1000,"height":564,"caption":"Boitedecom - Agence Web"},"image":{"@id":"https:\/\/boitedecom.ca\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Boitedecom\/","https:\/\/x.com\/boitedecomca","https:\/\/www.instagram.com\/boitedecom\/","https:\/\/www.linkedin.com\/company\/boitedecom","https:\/\/www.pinterest.com\/boitedecom\/","https:\/\/www.youtube.com\/user\/BoiteDeCom"]},{"@type":"Person","@id":"https:\/\/boitedecom.ca\/blog\/#\/schema\/person\/9a90a1bdb428bc354a4644e77d55d926","name":"Boitedecom","url":"https:\/\/boitedecom.ca\/blog\/author\/boitedecom\/"}]}},"_links":{"self":[{"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/posts\/820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/comments?post=820"}],"version-history":[{"count":0,"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/posts\/820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/media\/824"}],"wp:attachment":[{"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/media?parent=820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/categories?post=820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boitedecom.ca\/blog\/wp-json\/wp\/v2\/tags?post=820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}